{"id":50,"date":"2025-01-09T16:15:13","date_gmt":"2025-01-09T15:15:13","guid":{"rendered":"https:\/\/hydroleduc.com\/de\/?page_id=50"},"modified":"2025-09-30T15:09:24","modified_gmt":"2025-09-30T13:09:24","slug":"persoenliche-daten","status":"publish","type":"page","link":"https:\/\/hydroleduc.com\/de\/persoenliche-daten\/","title":{"rendered":"Pers\u00f6nliche Daten"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"50\" class=\"elementor elementor-50\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-750cc825 header-page e-flex e-con-boxed e-con e-parent\" data-id=\"750cc825\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5813e34d elementor-widget elementor-widget-breadcrumbs\" data-id=\"5813e34d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/hydroleduc.com\/de\/\">Startseite<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28bb734e elementor-widget elementor-widget-heading\" data-id=\"28bb734e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Pers\u00f6nliche Daten<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pers\u00f6nliche Daten<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-50","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pers\u00f6nliche Daten - Hydro Leduc<\/title>\n<meta name=\"description\" content=\"Pers\u00f6nliche Daten\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hydroleduc.com\/de\/persoenliche-daten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pers\u00f6nliche Daten - Hydro Leduc\" \/>\n<meta property=\"og:description\" content=\"Pers\u00f6nliche Daten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hydroleduc.com\/de\/persoenliche-daten\/\" \/>\n<meta property=\"og:site_name\" content=\"HYDRO LEDUC\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-30T13:09:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hydroleduc.com\\\/de\\\/persoenliche-daten\\\/\",\"url\":\"https:\\\/\\\/hydroleduc.com\\\/de\\\/persoenliche-daten\\\/\",\"name\":\"Pers\u00f6nliche Daten - Hydro Leduc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hydroleduc.com\\\/de\\\/#website\"},\"datePublished\":\"2025-01-09T15:15:13+00:00\",\"dateModified\":\"2025-09-30T13:09:24+00:00\",\"description\":\"Pers\u00f6nliche Daten\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hydroleduc.com\\\/de\\\/persoenliche-daten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hydroleduc.com\\\/de\\\/persoenliche-daten\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hydroleduc.com\\\/de\\\/persoenliche-daten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hydroleduc.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pers\u00f6nliche Daten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hydroleduc.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/hydroleduc.com\\\/de\\\/\",\"name\":\"HYDRO LEDUC\",\"description\":\"Hersteller von Hydraulikkomponenten\",\"publisher\":{\"@id\":\"https:\\\/\\\/hydroleduc.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hydroleduc.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hydroleduc.com\\\/de\\\/#organization\",\"name\":\"HYDRO LEDUC\",\"url\":\"https:\\\/\\\/hydroleduc.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hydroleduc.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hydroleduc.com\\\/de\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo-hydroleduc.png\",\"contentUrl\":\"https:\\\/\\\/hydroleduc.com\\\/de\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo-hydroleduc.png\",\"width\":366,\"height\":148,\"caption\":\"HYDRO LEDUC\"},\"image\":{\"@id\":\"https:\\\/\\\/hydroleduc.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pers\u00f6nliche Daten - Hydro Leduc","description":"Pers\u00f6nliche Daten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hydroleduc.com\/de\/persoenliche-daten\/","og_locale":"de_DE","og_type":"article","og_title":"Pers\u00f6nliche Daten - Hydro Leduc","og_description":"Pers\u00f6nliche Daten","og_url":"https:\/\/hydroleduc.com\/de\/persoenliche-daten\/","og_site_name":"HYDRO LEDUC","article_modified_time":"2025-09-30T13:09:24+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hydroleduc.com\/de\/persoenliche-daten\/","url":"https:\/\/hydroleduc.com\/de\/persoenliche-daten\/","name":"Pers\u00f6nliche Daten - Hydro Leduc","isPartOf":{"@id":"https:\/\/hydroleduc.com\/de\/#website"},"datePublished":"2025-01-09T15:15:13+00:00","dateModified":"2025-09-30T13:09:24+00:00","description":"Pers\u00f6nliche Daten","breadcrumb":{"@id":"https:\/\/hydroleduc.com\/de\/persoenliche-daten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hydroleduc.com\/de\/persoenliche-daten\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hydroleduc.com\/de\/persoenliche-daten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hydroleduc.com\/de\/"},{"@type":"ListItem","position":2,"name":"Pers\u00f6nliche Daten"}]},{"@type":"WebSite","@id":"https:\/\/hydroleduc.com\/de\/#website","url":"https:\/\/hydroleduc.com\/de\/","name":"HYDRO LEDUC","description":"Hersteller von Hydraulikkomponenten","publisher":{"@id":"https:\/\/hydroleduc.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hydroleduc.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/hydroleduc.com\/de\/#organization","name":"HYDRO LEDUC","url":"https:\/\/hydroleduc.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hydroleduc.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/hydroleduc.com\/de\/wp-content\/uploads\/2025\/01\/logo-hydroleduc.png","contentUrl":"https:\/\/hydroleduc.com\/de\/wp-content\/uploads\/2025\/01\/logo-hydroleduc.png","width":366,"height":148,"caption":"HYDRO LEDUC"},"image":{"@id":"https:\/\/hydroleduc.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hydroleduc.com\/de\/wp-json\/wp\/v2\/pages\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hydroleduc.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hydroleduc.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hydroleduc.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hydroleduc.com\/de\/wp-json\/wp\/v2\/comments?post=50"}],"version-history":[{"count":38,"href":"https:\/\/hydroleduc.com\/de\/wp-json\/wp\/v2\/pages\/50\/revisions"}],"predecessor-version":[{"id":45860,"href":"https:\/\/hydroleduc.com\/de\/wp-json\/wp\/v2\/pages\/50\/revisions\/45860"}],"wp:attachment":[{"href":"https:\/\/hydroleduc.com\/de\/wp-json\/wp\/v2\/media?parent=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}